{"id":3038,"date":"2020-04-24T08:53:35","date_gmt":"2020-04-24T08:53:35","guid":{"rendered":"http:\/\/the-codest.localhost\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/"},"modified":"2026-04-24T11:29:19","modified_gmt":"2026-04-24T11:29:19","slug":"un-regard-objectif-sur-la-guerre-des-bibliotheques-react-vs-vue","status":"publish","type":"post","link":"https:\/\/thecodest.co\/fr\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/","title":{"rendered":"Un regard objectif sur la guerre des biblioth\u00e8ques : React vs Vue"},"content":{"rendered":"<p><h2>D'o\u00f9 venons-nous ? Que sommes-nous ? O\u00f9 allons-nous ?<\/h2><\/p>\n<p>Arr\u00eatons-nous un instant et voyons o\u00f9 nous en sommes. En tant que baby-boomer, je doute sinc\u00e8rement qu'il y a une dizaine d'ann\u00e9es, quelqu'un aurait pu pr\u00e9dire que l'Europe serait en train de devenir une r\u00e9alit\u00e9. <a href=\"https:\/\/thecodest.co\/fr\/blog\/find-your-node-js-expert-for-hire-today\/\">d\u00e9veloppement web<\/a> irait aussi loin.<\/p>\n<p>Les applications bureautiques utilitaires appartiennent au pass\u00e9, car tout peut \u00eatre fait dans un navigateur. En fait, les applications qui doivent utiliser des API de niveau inf\u00e9rieur qui ne sont pas disponibles dans le navigateur sont \u00e9galement \u00e9crites \u00e0 l'aide de moteurs et de langages de navigateur parce qu'elles sont plus faciles \u00e0 maintenir.<\/p>\n<p>Les applications mobiles peuvent \u00eatre facilement remplac\u00e9es par des outils utilis\u00e9s pour <a href=\"https:\/\/thecodest.co\/fr\/blog\/find-your-ideal-stack-for-web-development\/\">web<\/a> d\u00e9veloppement - voir <strong><a href=\"https:\/\/thecodest.co\/fr\/blog\/conditional-component-visibility-in-react\/\">React<\/a> Natif<\/strong>NativeScript. En outre, nous avons les PWA, qui \"imitent\" facilement le fonctionnement des applications mobiles. En outre, les composants qui alimentent une application \u00e9crite en <strong><a href=\"https:\/\/thecodest.co\/fr\/blog\/hire-vue-js-developers\/\">Vue<\/a><\/strong> ou <strong>React<\/strong> peut facilement partager divers <a href=\"https:\/\/thecodest.co\/fr\/dictionary\/what-is-code-refactoring\/\">code<\/a> entre les plateformes. <\/p>\n<p>Nous devons admettre une chose : les applications web sont actuellement une puissance qu'il sera difficile de faire redescendre au rez-de-chauss\u00e9e. En tant qu'utilisateur, je me vois les utiliser pratiquement partout : communiquer via Slack, utiliser un \u00e9diteur de code, faire des pr\u00e9sentations ou m\u00eame \u00e9crire un article de blog.<\/p>\n<p>Il est difficile de pr\u00e9dire ce qui se passera dans quelques ann\u00e9es. WebAssembly est en train d'entrer en jeu, et il permettra \u00e0 <a href=\"https:\/\/thecodest.co\/fr\/blog\/why-us-companies-are-opting-for-polish-developers\/\">nous<\/a> de transf\u00e9rer les applications qui n\u00e9cessitent des calculs plus complexes dans le monde des navigateurs. Un fait demeure toutefois inchang\u00e9 : il est vraiment difficile de trouver un obstacle \u00e0 la cr\u00e9ation, \u00e0 l'aide des technologies web, d'une application dont nous ne pouvons que r\u00eaver. <\/p>\n<p><h2>Le big bang dans la r\u00e9alit\u00e9 de l'internet <\/h2><\/p>\n<p>Revenons un instant en arri\u00e8re, avant que n'apparaissent les premiers cadres web plus importants et que les applications ne soient d\u00e9velopp\u00e9es de mani\u00e8re imp\u00e9rative. Chaque m\u00e9canisme interactif d'une page \u00e9tait g\u00e9r\u00e9 manuellement et \u00e9tait responsable d'une action sp\u00e9cifique.<\/p>\n<p>Le meilleur exemple que l'on puisse citer est la biblioth\u00e8que jQuery, qui \u00e9tait \u00e0 l'\u00e9poque l'une des solutions les plus populaires pour g\u00e9rer des \u00e9v\u00e9nements simples. Gr\u00e2ce \u00e0 elle, divers menus d\u00e9roulants, transitions, animations, calculatrices et autres m\u00e9canismes similaires ont \u00e9t\u00e9 mis en \u0153uvre.<\/p>\n<p>Il convient de mentionner que des probl\u00e8mes dans des applications plus complexes ont d\u00e9j\u00e0 \u00e9t\u00e9 constat\u00e9s \u00e0 l'\u00e9poque - l\u00e0 o\u00f9 diff\u00e9rentes parties ind\u00e9pendantes devaient, par exemple, r\u00e9agir \u00e0 un clic appropri\u00e9 ou \u00e0 la frappe d'un texte. La plupart des applications n'avaient pas d'\u00e9tat explicite et \u00e9taient sauv\u00e9es, par exemple, par les attributs des \u00e9l\u00e9ments ou les classes qu'ils poss\u00e9daient.<\/p>\n<p>\u00c0 l'\u00e9poque, il \u00e9tait clair que l'approche actuelle manquait de r\u00e9activit\u00e9 - une mani\u00e8re structur\u00e9e pour les composants de communiquer entre eux et de partager, par exemple, leur \u00e9tat ou diff\u00e9rents \u00e9v\u00e9nements, ce qui rendait les applications plus faciles \u00e0 maintenir et leur permettait d'offrir une bonne exp\u00e9rience \u00e0 l'utilisateur \u00e0 un faible co\u00fbt.<\/p>\n<p><article-digital-product-development><\/article-digital-product-development><\/p>\n<p><h2>Premiers pas vers des cadres bien connus<\/h2><\/p>\n<p>Au fil du temps, les premiers cadres frontaux ont commenc\u00e9 \u00e0 appara\u00eetre \u00e0 l'horizon, visant \u00e0 structurer l'architecture pour des applications plus complexes.<\/p>\n<p>Ces frameworks \u00e9taient principalement bas\u00e9s sur le mod\u00e8le MVC - certains proposaient une approche plus manuelle, comme Backbone.js, tandis que d'autres, comme Knockout.js, s'accrochaient \u00e0 des syst\u00e8mes de gestion de l'information \u00e0 double sens. <a href=\"https:\/\/thecodest.co\/fr\/blog\/app-data-collection-security-risks-value-and-types-explored\/\">donn\u00e9es<\/a> de la reliure.<\/p>\n<p>Cependant, on peut estimer que la r\u00e9daction de l'application \u00e9tait plus difficile, qu'elle n\u00e9cessitait beaucoup plus de codage et qu'elle ne produisait pas n\u00e9cessairement les r\u00e9sultats escompt\u00e9s ou ne compensait pas le temps perdu dans le d\u00e9veloppement de l'application.<\/p>\n<p>La principale raison pour laquelle la recherche de la moyenne d'or dans le <a href=\"https:\/\/thecodest.co\/fr\/blog\/javascript-tools-in-action\/\">JS<\/a> L'\u00e9cosyst\u00e8me \u00e9tait difficile, car il s'agissait d'une bizarrerie parmi des <a href=\"https:\/\/thecodest.co\/fr\/blog\/top-programming-languages-to-build-e-commerce\/\">les langages de programmation<\/a> qui ont depuis longtemps trac\u00e9 leur chemin.<\/p>\n<p>Et je ne veux pas m'attarder ici sur les chemins qui ont accompagn\u00e9 le d\u00e9veloppement des diff\u00e9rents frameworks tout au long de l'histoire. Cependant, il est important de noter une chose : la maturation de l'\u00e9cosyst\u00e8me JS dans les navigateurs n'a pas \u00e9t\u00e9 facile et a d\u00fb faire face \u00e0 de nombreuses \u00e9preuves.<\/p>\n<p>C'est la seule raison pour laquelle nous pouvons aujourd'hui cr\u00e9er des applications web et les d\u00e9velopper d'une mani\u00e8re tr\u00e8s simple et sans douleur.<\/p>\n<p><h2>Informations de base et l\u00e9g\u00e8re comparaison<\/h2><\/p>\n<p>Au lieu de jeter de la viande, comme il est d'usage sur l'internet, examinons les deux biblioth\u00e8ques, rassemblons des informations \u00e0 leur sujet et comparons-les, tant en th\u00e9orie qu'en pratique.<\/p>\n<p>NOTE : La description des m\u00e9canismes fonctionnant en <strong>Vue <\/strong>se r\u00e9f\u00e8re sp\u00e9cifiquement \u00e0 la version 2. La version 3 introduit un grand nombre de changements significatifs, mais n'est pas un v\u00e9ritable concurrent de la <strong>React<\/strong> pour le moment, ne serait-ce qu'en raison de sa maturit\u00e9 - Vue 3 date de sortie : 18 septembre 2020.<\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2024\/05\/tabela-art-.jpg\" alt=\"React Vue diff\u00e9rences \" \/><\/p>\n<p>Soyons clairs : en creusant plus profond\u00e9ment dans les deux biblioth\u00e8ques, vous pouvez voir qu'il y a en fait plus de similitudes que de diff\u00e9rences. En laissant de c\u00f4t\u00e9 la mani\u00e8re d'utiliser les biblioth\u00e8ques en tant que telles, elles ont toutes deux des concepts de fonctionnement tr\u00e8s similaires. Elles sont toutes deux aliment\u00e9es par un \u00e9cosyst\u00e8me similaire et leur utilisation n'est pas diam\u00e9tralement diff\u00e9rente.<\/p>\n<p>\u25cf Le diable se cache dans les d\u00e9tails - plus nous utilisons un outil, plus nous remarquons les inconv\u00e9nients de ses diff\u00e9rentes solutions. Un bon exemple est celui de la liaison bidirectionnelle des donn\u00e9es, qui est le plus souvent utilis\u00e9e dans les domaines suivants <strong>Vue<\/strong> en tant que propri\u00e9t\u00e9 du mod\u00e8le v : elle facilite souvent les choses, prend en charge un grand nombre d'\u00e9l\u00e9ments automatiquement et ne n\u00e9cessite pas de coder un support suppl\u00e9mentaire pour la modification des valeurs.<\/p>\n<p>Toutefois, dans certains cas, il est n\u00e9cessaire de suivre sp\u00e9cifiquement une tentative de changement et de r\u00e9agir en cons\u00e9quence. <strong>Vue<\/strong> Les effets m\u00e9caniques, tels que les propri\u00e9t\u00e9s calcul\u00e9es, font que l'effet obtenu est souvent bien pire qu'avec une approche manuelle ;<\/p>\n<p>\u25cf Un autre aspect int\u00e9ressant est le JSX, qui est une mani\u00e8re tr\u00e8s \"vagabonde\" de mod\u00e9liser le contenu rendu \u00e0 l'aide de <strong>React<\/strong>. Les avis divergent au sein de la communaut\u00e9 des d\u00e9veloppeurs.<\/p>\n<p>D'apr\u00e8s mes observations, il semble que les d\u00e9veloppeurs qui utilisent un environnement autre que JS, par ex. <a href=\"https:\/\/thecodest.co\/fr\/dictionary\/how-to-hire-a-php-developer\/\">PHP<\/a> ou C#, sont plus enclins \u00e0 mod\u00e9liser les points de vue de mani\u00e8re \u00e0 ce qu'ils soient plus faciles \u00e0 comprendre. <strong>Vue<\/strong> ne.<\/p>\n<p>En r\u00e9sum\u00e9, les mod\u00e8les connus de <strong>Vue<\/strong> permettent de d\u00e9finir des vues de mani\u00e8re tr\u00e8s claire et \u00e9l\u00e9gante, tandis que le JSX de React permet de les construire dans de nombreux cas plus rapidement, en les adaptant \u00e0 des besoins sp\u00e9cifiques et en n\u00e9cessitant souvent moins de code pour construire des structures diverses ;<\/p>\n<p>\u25cf Examinons \u00e9galement les \u00e9cosyst\u00e8mes de ces deux outils. En principe, nous pouvons dire qu'ils ne diff\u00e8rent en rien. Tous deux sont appel\u00e9s biblioth\u00e8ques pour une raison : ils fournissent le strict minimum pour la prise en charge d'applications web r\u00e9actives.<\/p>\n<p>Tandis que les autres, li\u00e9s \u00e0 la communication avec les <a href=\"https:\/\/thecodest.co\/fr\/blog\/compare-staff-augmentation-firms-that-excel-in-api-team-staffing-for-financial-technology-projects\/\">API<\/a>, Le flux de donn\u00e9es, les composants de l'interface utilisateur utilis\u00e9s dans les diff\u00e9rentes sous-pages, sont les \"vendeurs\" - des biblioth\u00e8ques externes qui doivent \u00eatre correctement rattach\u00e9es \u00e0 l'interface utilisateur. <a href=\"https:\/\/thecodest.co\/fr\/dictionary\/why-do-projects-fail\/\">projet<\/a>. C'est un peu comme le monde des Lego : si vous voulez construire un ensemble coh\u00e9rent, vous devez l'assembler \u00e0 partir de petits blocs individuels.<\/p>\n<p>Cette all\u00e9gorie se r\u00e9f\u00e8re pr\u00e9cis\u00e9ment aux composants attach\u00e9s, qui sont la force des applications cr\u00e9\u00e9es avec <strong>React<\/strong> ou <strong>Vue<\/strong>;<\/p>\n<p>\u25cf Une chose importante, en particulier pour les personnes qui ne sont pas tr\u00e8s exp\u00e9riment\u00e9es dans l'environnement JS, est le niveau d'entr\u00e9e dans une biblioth\u00e8que particuli\u00e8re. En d'autres termes - la complexit\u00e9 de l'outil, consistant en le temps direct que vous devez consacrer \u00e0 la compr\u00e9hension de ses m\u00e9canismes.<\/p>\n<p>Je pense qu'une chose doit \u00eatre dite sans \u00e9quivoque : dans le cas de la <strong>Vue<\/strong>Il est beaucoup plus simple. Nous avons une liaison de donn\u00e9es bidirectionnelle, nous avons un mod\u00e8le \u00e9l\u00e9gamment sp\u00e9cifi\u00e9 qui est trompeusement similaire aux solutions dans d'autres langages, par exemple twig, et enfin - nous n'avons pas de maux de t\u00eate caus\u00e9s par l'apprentissage des th\u00e9ories concernant le fonctionnement des crochets individuels et les cas dans lesquels des m\u00e9canismes sp\u00e9cifiques doivent \u00eatre utilis\u00e9s.<\/p>\n<p><h2>Que disent les statistiques ?<\/h2><\/p>\n<p>S'aligner directement sur la voix de la foule n'est pas exactement un bon choix. Cependant, une bonne \u00e9tape pour prendre une bonne d\u00e9cision est d'analyser ce que disent les personnes qui ont interagi avec ces biblioth\u00e8ques.<\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2024\/05\/bez-tytulu.png\" alt=\"vue js graph\" \/><\/p>\n<p>Et oui -  <a href=\"https:\/\/star-history.t9t.io\/#facebook\/react&amp;vuejs\/vue\" rel=\"nofollow\">\u00e9toiles sur github <\/a> peut \u00eatre un indicateur du degr\u00e9 d'implication de la communaut\u00e9 d'une biblioth\u00e8que donn\u00e9e dans son d\u00e9veloppement, de la mani\u00e8re dont elle est per\u00e7ue par les d\u00e9veloppeurs et de l'int\u00e9r\u00eat qu'ils portent \u00e0 son \u00e9volution. <a href=\"https:\/\/thecodest.co\/fr\/blog\/team-extension-guide-software-development\/\">Ing\u00e9nieurs<\/a> qui d\u00e9marrent un d\u00e9p\u00f4t particulier re\u00e7oivent souvent des notifications sur les nouvelles versions ou les changements de code, ce qui se traduit par une connaissance directe de la biblioth\u00e8que.<\/p>\n<p>Cependant, le nombre d'\u00e9toiles sur github ne doit pas \u00eatre consid\u00e9r\u00e9 comme un oracle - tous les d\u00e9veloppeurs qui aiment un outil ne laisseront pas une marque - mais plut\u00f4t comme un signe de la passion pure que les d\u00e9veloppeurs ont pour un projet open-source particulier.<\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2024\/05\/aaaaaabbb.png\" alt=\"react vs. vue \" \/><\/p>\n<p><a href=\"https:\/\/trends.google.com\/trends\/explore?date=today%205-y&amp;q=react%20js,vue%20js\" rel=\"nofollow\">Google Trends <\/a> est un service bien connu qui permet d'\u00e9tudier l'int\u00e9r\u00eat pour des sujets sp\u00e9cifiques au fil du temps. Bien qu'il ne s'agisse pas d'un indicateur rationnel de la qualit\u00e9 ou de l'utilisation, il peut fournir toutes sortes d'analyses.<\/p>\n<p>Il est facile de constater que le parcours des cinq derni\u00e8res ann\u00e9es a \u00e9t\u00e9 relativement similaire lorsqu'il s'agit de comparer les deux protagonistes de l'article d'aujourd'hui. La conclusion de base que l'on peut tirer de ce tableau est que<strong> React<\/strong> est plus performant en termes de popularit\u00e9 de recherche par rapport \u00e0 son adversaire.<\/p>\n<p>Pour \u00eatre clair, le fait d'\u00eatre en t\u00eate de Google Trends ne signifie pas qu'une biblioth\u00e8que est meilleure. Il s'agit de la popularit\u00e9 du public, comme je l'ai mentionn\u00e9 pr\u00e9c\u00e9demment - probablement plus de personnes ont entendu parler de cet outil, il a peut-\u00eatre suscit\u00e9 plus d'int\u00e9r\u00eat parmi les membres de l'Union europ\u00e9enne. <a href=\"https:\/\/thecodest.co\/fr\/blog\/guide-to-enterprise-software-development\/\">CTOs<\/a>, <strong><a href=\"https:\/\/thecodest.co\/fr\/blog\/hire-software-developers\/\">d\u00e9veloppeurs de logiciels<\/a> <\/strong>ou les personnes qui souhaitent simplement apprendre un outil particulier.<\/p>\n<p>Ce graphique se refl\u00e8te-t-il dans la r\u00e9alit\u00e9 ? Dans une certaine mesure, oui. D'une mani\u00e8re g\u00e9n\u00e9rale, les personnes interrog\u00e9es sont plus nombreuses \u00e0 faire preuve d'une connaissance diversifi\u00e9e et sophistiqu\u00e9e des sujets suivants <strong>React<\/strong> que <strong>Vue<\/strong>. Quelles opinions pouvez-vous obtenir en parlant avec ces personnes ? J'essaierai d'en donner un aper\u00e7u dans le paragraphe suivant.<\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2024\/05\/1.png\" alt=\"Classement des cadres\" \/><\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2024\/05\/2.png\" alt=\"\u00e9tat de la JS \" \/><\/p>\n<p><img decoding=\"async\" src=\"\/app\/uploads\/2024\/05\/3.png\" alt=\"React vs. Vue \" \/><\/p>\n<p><a href=\"https:\/\/2020.stateofjs.com\/en-US\/\" rel=\"nofollow\">\u00c9tat de la JS\u00a0<\/a> est un site qui interroge chaque ann\u00e9e les personnes travaillant sur les technologies li\u00e9es \u00e0 JavaScript. Son objectif est de recueillir des informations aupr\u00e8s des d\u00e9veloppeurs sur la mani\u00e8re dont ils per\u00e7oivent les outils avec lesquels ils travaillent au quotidien.<\/p>\n<p>Les questions couvrent des outils individuels pour diff\u00e9rents objectifs - par exemple, des outils utilis\u00e9s sur le front-end et sur le back-end, mais aussi des outils pour les tests, la gestion de l'\u00e9tat de l'application, etc. Le site pose une s\u00e9rie de questions sur l'outil lui-m\u00eame, les int\u00e9r\u00eats, les exp\u00e9riences et une \u00e9valuation globale qui se r\u00e9sume \u00e0 la phrase \"Utiliseriez-vous cet outil dans de futurs projets ?\"<\/p>\n<p>Le site lui-m\u00eame vous permet de faire de nombreuses analyses, de comparer des outils pertinents et parfois de d\u00e9couvrir des biblioth\u00e8ques moins connues qui commencent \u00e0 bien se comporter dans le monde du JS, gagnant en popularit\u00e9 tout en b\u00e9n\u00e9ficiant d'un taux de \"bonheur d'utilisation\" \u00e9lev\u00e9. Je vous encourage sinc\u00e8rement \u00e0 parcourir le contenu de ce site.<\/p>\n<p>R\u00e9sumons la section \u00e0 l'aide de statistiques. L'analyse de diff\u00e9rents types de graphiques peut souvent \u00eatre une tr\u00e8s bonne option pour comparer diff\u00e9rents aspects de sujets donn\u00e9s. Cependant, il est important de prendre en compte le fait que suivre la voix de la foule n'est pas n\u00e9cessairement la chose la plus intelligente \u00e0 faire. Au lieu de cela, vous pouvez prendre une d\u00e9cision \u00e9clair\u00e9e en utilisant certaines des le\u00e7ons tir\u00e9es des analyses de graphiques.<\/p>\n<p><h2>Meilleur choix pour les d\u00e9veloppeurs<\/h2><\/p>\n<p>J'ai mentionn\u00e9 plus haut le seuil d'entr\u00e9e plus bas pour l'obtention d'un permis de conduire. <strong>Vue<\/strong> - En effet, il permet de se concentrer un peu plus rapidement sur le d\u00e9veloppement de l'application, en utilisant l'outil et en r\u00e9duisant au minimum le temps n\u00e9cessaire pour se familiariser avec l'environnement, les m\u00e9canismes et les diff\u00e9rents cas d'utilisation.<\/p>\n<p>D'une mani\u00e8re g\u00e9n\u00e9rale, je suis d'avis que <strong>Vue<\/strong> est plus adapt\u00e9 aux personnes qui n'ont pas encore eu affaire \u00e0 des biblioth\u00e8ques frontales. Il vous permettra certainement d'obtenir des r\u00e9sultats satisfaisants en peu de temps d'une mani\u00e8re plus encourageante.<\/p>\n<p>Cependant, disons-le haut et fort, la m\u00e9connaissance du langage dans lequel nous utilisons des outils sp\u00e9cifiques nous portera pr\u00e9judice t\u00f4t ou tard. C'est un \u00e9l\u00e9ment n\u00e9gligeable pour les choses simples, mais au fur et \u00e0 mesure que la complexit\u00e9 des applications cr\u00e9\u00e9es augmente, il sera de plus en plus difficile de construire des applications de mani\u00e8re d\u00e9cente sans une bonne connaissance des \u00e9l\u00e9ments suivants <a href=\"https:\/\/thecodest.co\/fr\/blog\/hire-javascript-developer\/\">JavaScript<\/a>.<\/p>\n<p>Je ne fais pas vraiment r\u00e9f\u00e9rence \u00e0 la capacit\u00e9 d'\u00e9crire des fonctions sophistiqu\u00e9es, car cette partie peut \u00eatre largement remplac\u00e9e, par exemple, par des vendeurs. Je fais r\u00e9f\u00e9rence \u00e0 certaines erreurs courantes qui peuvent \u00eatre commises dans le langage et au fait de ne pas \u00eatre conscient que le comportement incorrect n'est pas d\u00fb \u00e0 l'utilisation de la biblioth\u00e8que, mais \u00e0 l'utilisation du langage. L'erreur la plus courante qui se manifeste ici est la soi-disant immutabilit\u00e9 - c'est-\u00e0-dire la connaissance du m\u00e9canisme de r\u00e9f\u00e9rence dans JavaScript.<\/p>\n<p>Je ne suis pas en mesure de dire quelle biblioth\u00e8que est la meilleure pour les d\u00e9veloppeurs plus ou moins familiers avec JavaScript. Mais je sais une chose : si vous voulez avoir une id\u00e9e r\u00e9elle de la fa\u00e7on dont le d\u00e9veloppement avec les deux outils se pr\u00e9sente \"de l'int\u00e9rieur\", essayez d'\u00e9crire des applications dans chacun d'entre eux. Cela vous donnera une id\u00e9e, vous permettra de voir quels m\u00e9canismes vous attirent le plus et quel est le meilleur choix pour vous.<\/p>\n<p>Comme je l'ai mentionn\u00e9 pr\u00e9c\u00e9demment, les deux biblioth\u00e8ques sont aliment\u00e9es par des \u00e9cosyst\u00e8mes similaires et ont une vision similaire de la construction d'applications avec de petits composants. Les deux biblioth\u00e8ques se portent bien - rien n'indique qu'elles dispara\u00eetront dans un avenir proche. Par cons\u00e9quent, les offres d'emploi dans les deux biblioth\u00e8ques resteront \u00e0 un niveau similaire.<\/p>\n<p>Les conclusions sont simples : utilisez ce qui vous convient, accumulez de l'exp\u00e9rience et \u00e9valuez. Cela vous aidera \u00e0 d\u00e9velopper une approche rationnelle pour d\u00e9terminer s'il est pr\u00e9f\u00e9rable d'utiliser l'une ou l'autre biblioth\u00e8que dans le cadre d'un projet particulier ; essayez \u00e9galement d'exp\u00e9rimenter - rien n'enseigne aussi profond\u00e9ment que les erreurs commises dans le pass\u00e9.<\/p>\n<p><h2>Meilleur choix pour <a href=\"https:\/\/thecodest.co\/fr\/blog\/ainiros-cto-discusses-the-hurdles-and-successes-in-crafting-ai-driven-solutions\/\">CTO<\/a> <\/h2><\/p>\n<p>Ce n'est un secret pour personne qu'il n'existe pas de solution miracle qui soit la meilleure pour un projet particulier. Les outils utilis\u00e9s pour cr\u00e9er des applications vieillissent rapidement, surtout au niveau du front-end, et il est souvent difficile de trouver ses marques dans les derni\u00e8res tendances.<\/p>\n<p>Cependant, le choix de la technologie n'est pas, ou du moins ne devrait pas \u00eatre, une question d'ad\u00e9quation avec les tendances actuelles. Nous devrions plut\u00f4t l'orienter vers des attentes et des hypoth\u00e8ses sp\u00e9cifiques concernant l'application que nous allons construire. Chacune des biblioth\u00e8ques compar\u00e9es a ses forces et ses faiblesses, qui, adapt\u00e9es au cas d'utilisation, nous permettront de faire le choix le plus raisonnable.<\/p>\n<p>Une option int\u00e9ressante pourrait \u00eatre les r\u00e9sum\u00e9s technologiques des grandes entreprises, qui d\u00e9crivent souvent leurs cas d'utilisation, la mani\u00e8re dont le d\u00e9veloppement d'applications importantes s'est d\u00e9roul\u00e9 ou se d\u00e9roule actuellement et les erreurs qu'elles ont commises dans le pass\u00e9. Peut-\u00eatre trouverons-nous parmi eux des cas particuli\u00e8rement int\u00e9ressants dans le contexte du choix d'une biblioth\u00e8que pour un projet particulier.<\/p>\n<p>Les caract\u00e9ristiques \u00e0 prendre en compte pour choisir les bons outils pour l'application en cours de d\u00e9veloppement sont : le temps de d\u00e9veloppement de l'application, la facilit\u00e9 d'utilisation de l'outil, la facilit\u00e9 d'utilisation de l'outil, la facilit\u00e9 d'utilisation de l'outil. <a href=\"https:\/\/thecodest.co\/fr\/blog\/the-importance-of-regular-application-maintenance-and-support-in-future-proofing-your-business\/\">maintenance de l'application<\/a>Le choix des biblioth\u00e8ques d\u00e9pend de plusieurs facteurs : la complexit\u00e9 de l'application et l'exp\u00e9rience des d\u00e9veloppeurs dans l'utilisation de biblioth\u00e8ques sp\u00e9cifiques.<\/p>\n<p>Les d\u00e9veloppeurs sont les personnes qui passent le plus de temps avec les outils que je compare et ce sont eux qui peuvent fournir les meilleurs conseils et vous aider \u00e0 faire le meilleur choix dans le grand choc des biblioth\u00e8ques. C'est au cours du d\u00e9veloppement de l'application que l'on voit les diff\u00e9rents probl\u00e8mes qui d\u00e9coulent directement du choix de la technologie, et que l'on a la meilleure vue sur ce qui nuit \u00e0 l'utilisation d'un outil particulier pour des fonctionnalit\u00e9s particuli\u00e8res.<\/p>\n<p>Comme je l'ai mentionn\u00e9 pr\u00e9c\u00e9demment, les deux biblioth\u00e8ques ne semblent pas dispara\u00eetre de la base de donn\u00e9es de la <a href=\"https:\/\/thecodest.co\/fr\/dictionary\/what-is-the-size-of-your-potential-reachable-market\/\">march\u00e9<\/a>Il n'est pas possible de prendre des d\u00e9cisions sur la base de statistiques ou d'opinions, du moins pas dans les ann\u00e9es \u00e0 venir. Au lieu de prendre des d\u00e9cisions bas\u00e9es sur des statistiques et des opinions<br \/>\nde diverses personnes sur l'internet - il serait peut-\u00eatre plus judicieux de s'adresser aux d\u00e9veloppeurs.<\/p>\n<p>Nous leur pr\u00e9sentons ce que nous attendons de l'application, le temps dont nous disposons pour la livrer et nous leur permettons d'\u00e9changer librement leurs points de vue sur les deux solutions avant de prendre une d\u00e9cision finale.<\/p>\n<p><h2>Conclusions<\/h2><\/p>\n<p>Les guerres sur l'internet sont g\u00e9n\u00e9ralement - ou peut-\u00eatre dans tous les cas - inutiles. Il y aura toujours des personnes qui s'ent\u00eateront \u00e0 affirmer que leur choix est meilleur sans donner d'arguments rationnels confirmant leur d\u00e9cision.<\/p>\n<p>Au lieu de nous laisser aveugler par des choix sp\u00e9cifiques, concentrons-nous sur l'analyse, essayons de tirer des conclusions appropri\u00e9es et utilisons-les pour ajuster ou rejeter une solution sp\u00e9cifique.<\/p>\n<p>Comme le titre l'indique, je n'ai pas l'intention de couronner une biblioth\u00e8que particuli\u00e8re comme rem\u00e8de \u00e0 tous les maux. Au lieu de cela, quelques hypoth\u00e8ses sont pr\u00e9sent\u00e9es et les points forts et faibles des deux biblioth\u00e8ques sont r\u00e9v\u00e9l\u00e9s. J'ai donn\u00e9 quelques conseils sur ce qu'il faut rechercher lors du choix de l'une ou l'autre biblioth\u00e8que afin de prendre une d\u00e9cision judicieuse et de ne pas se laisser guider par les tendances ou par des personnes al\u00e9atoires sur l'internet.<\/p>\n<p>Chaque outil peut r\u00e9pondre aux besoins du projet de mani\u00e8re satisfaisante. Aucun des deux ne dispara\u00eetra rapidement du march\u00e9 dans les ann\u00e9es \u00e0 venir. Ils disposent tous deux de communaut\u00e9s puissantes et d'une certaine maturit\u00e9, ce qui montre qu'ils se portent bien.<\/p>\n<p>Le choix final est entre vos mains. Toutefois, si vous avez des doutes ou si vous souhaitez simplement discuter de votre cas avec <a href=\"https:\/\/thecodest.co\/fr\/blog\/vibrant-upturn-charting-the-resolute-rise-of-swedish-firms\/\">The Codest<\/a> - n'h\u00e9sitez pas \u00e0 nous contacter !<\/p>\n<p><article-product-development-consulting><\/article-product-development-consulting><\/p>\n<p><b>En savoir plus :<\/b><\/p>\n<p><a href=\"https:\/\/thecodest.co\/blog\/why-you-should-probably-use-typescript\">Pourquoi vous devriez (probablement) utiliser Typescript<\/a><\/p>\n<p><a href=\"https:\/\/thecodest.co\/blog\/how-not-to-kill-a-project-with-bad-coding-practices\/\">Comment ne pas tuer un projet avec de mauvaises pratiques de codage ?<\/a><\/p>\n<p><a href=\"https:\/\/thecodest.co\/blog\/data-fetching-strategies-in-nextjs\/\">Strat\u00e9gies de r\u00e9cup\u00e9ration des donn\u00e9es dans NextJS<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La croissance explosive du web, qui a commenc\u00e9 il y a environ 10 ans, a provoqu\u00e9 une grande confusion dans le monde de l'internet. Non seulement il a permis de faire plus de choses dans le navigateur, mais il a aussi chang\u00e9 la vision g\u00e9n\u00e9rale du d\u00e9veloppement d'applications. Cependant, cette approche a n\u00e9cessit\u00e9 quelques am\u00e9liorations dans la maintenance du code des applications bas\u00e9es sur le navigateur. C'est \u00e0 cette \u00e9poque qu'ont \u00e9t\u00e9 d\u00e9velopp\u00e9s les premiers frameworks frontaux. Je vais en analyser deux \u00e0 la loupe aujourd'hui.<\/p>","protected":false},"author":2,"featured_media":3039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software-development"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>An objective look at the library war: React vs Vue - The Codest<\/title>\n<meta name=\"description\" content=\"The explosive growth of the web that has started about 10 years ago has caused great confusion in the world of the internet. Not only did it make it possible to do more things in the browser, but also changed the general view of application development. However, this approach required some improvements in maintaining the code of browser-based applications. This was the time of development of the first front-end frameworks. I will analyse two of them under the microscope today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thecodest.co\/fr\/blog\/un-regard-objectif-sur-la-guerre-des-bibliotheques-react-vs-vue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An objective look at the library war: React vs Vue\" \/>\n<meta property=\"og:description\" content=\"The explosive growth of the web that has started about 10 years ago has caused great confusion in the world of the internet. Not only did it make it possible to do more things in the browser, but also changed the general view of application development. However, this approach required some improvements in maintaining the code of browser-based applications. This was the time of development of the first front-end frameworks. I will analyse two of them under the microscope today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thecodest.co\/fr\/blog\/un-regard-objectif-sur-la-guerre-des-bibliotheques-react-vs-vue\/\" \/>\n<meta property=\"og:site_name\" content=\"The Codest\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-24T08:53:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T11:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/react_vs_vue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"thecodest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"thecodest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/\"},\"author\":{\"name\":\"thecodest\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/person\\\/7e3fe41dfa4f4e41a7baad4c6e0d4f76\"},\"headline\":\"An objective look at the library war: React vs Vue\",\"datePublished\":\"2020-04-24T08:53:35+00:00\",\"dateModified\":\"2026-04-24T11:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/\"},\"wordCount\":2808,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/react_vs_vue.jpg\",\"articleSection\":[\"Software Development\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/\",\"url\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/\",\"name\":\"An objective look at the library war: React vs Vue - The Codest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/react_vs_vue.jpg\",\"datePublished\":\"2020-04-24T08:53:35+00:00\",\"dateModified\":\"2026-04-24T11:29:19+00:00\",\"description\":\"The explosive growth of the web that has started about 10 years ago has caused great confusion in the world of the internet. Not only did it make it possible to do more things in the browser, but also changed the general view of application development. However, this approach required some improvements in maintaining the code of browser-based applications. This was the time of development of the first front-end frameworks. I will analyse two of them under the microscope today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/react_vs_vue.jpg\",\"contentUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/react_vs_vue.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/an-objective-look-at-the-library-war-react-vs-vue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thecodest.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An objective look at the library war: React vs Vue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#website\",\"url\":\"https:\\\/\\\/thecodest.co\\\/\",\"name\":\"The Codest\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thecodest.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#organization\",\"name\":\"The Codest\",\"url\":\"https:\\\/\\\/thecodest.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/03\\\/thecodest-logo.svg\",\"contentUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/03\\\/thecodest-logo.svg\",\"width\":144,\"height\":36,\"caption\":\"The Codest\"},\"image\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pl.linkedin.com\\\/company\\\/codest\",\"https:\\\/\\\/clutch.co\\\/profile\\\/codest\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/person\\\/7e3fe41dfa4f4e41a7baad4c6e0d4f76\",\"name\":\"thecodest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g\",\"caption\":\"thecodest\"},\"url\":\"https:\\\/\\\/thecodest.co\\\/fr\\\/author\\\/thecodest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un regard objectif sur la guerre des biblioth\u00e8ques : React vs Vue - The Codest","description":"La croissance explosive du web, qui a commenc\u00e9 il y a environ 10 ans, a provoqu\u00e9 une grande confusion dans le monde de l'internet. Non seulement il a permis de faire plus de choses dans le navigateur, mais il a aussi chang\u00e9 la vision g\u00e9n\u00e9rale du d\u00e9veloppement d'applications. Cependant, cette approche a n\u00e9cessit\u00e9 quelques am\u00e9liorations dans la maintenance du code des applications bas\u00e9es sur le navigateur. C'est \u00e0 cette \u00e9poque qu'ont \u00e9t\u00e9 d\u00e9velopp\u00e9s les premiers frameworks frontaux. Je vais en analyser deux \u00e0 la loupe aujourd'hui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thecodest.co\/fr\/blog\/un-regard-objectif-sur-la-guerre-des-bibliotheques-react-vs-vue\/","og_locale":"fr_FR","og_type":"article","og_title":"An objective look at the library war: React vs Vue","og_description":"The explosive growth of the web that has started about 10 years ago has caused great confusion in the world of the internet. Not only did it make it possible to do more things in the browser, but also changed the general view of application development. However, this approach required some improvements in maintaining the code of browser-based applications. This was the time of development of the first front-end frameworks. I will analyse two of them under the microscope today.","og_url":"https:\/\/thecodest.co\/fr\/blog\/un-regard-objectif-sur-la-guerre-des-bibliotheques-react-vs-vue\/","og_site_name":"The Codest","article_published_time":"2020-04-24T08:53:35+00:00","article_modified_time":"2026-04-24T11:29:19+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/react_vs_vue.jpg","type":"image\/jpeg"}],"author":"thecodest","twitter_card":"summary_large_image","twitter_misc":{"Written by":"thecodest","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#article","isPartOf":{"@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/"},"author":{"name":"thecodest","@id":"https:\/\/thecodest.co\/#\/schema\/person\/7e3fe41dfa4f4e41a7baad4c6e0d4f76"},"headline":"An objective look at the library war: React vs Vue","datePublished":"2020-04-24T08:53:35+00:00","dateModified":"2026-04-24T11:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/"},"wordCount":2808,"commentCount":0,"publisher":{"@id":"https:\/\/thecodest.co\/#organization"},"image":{"@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#primaryimage"},"thumbnailUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/react_vs_vue.jpg","articleSection":["Software Development"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/","url":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/","name":"Un regard objectif sur la guerre des biblioth\u00e8ques : React vs Vue - The Codest","isPartOf":{"@id":"https:\/\/thecodest.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#primaryimage"},"image":{"@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#primaryimage"},"thumbnailUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/react_vs_vue.jpg","datePublished":"2020-04-24T08:53:35+00:00","dateModified":"2026-04-24T11:29:19+00:00","description":"La croissance explosive du web, qui a commenc\u00e9 il y a environ 10 ans, a provoqu\u00e9 une grande confusion dans le monde de l'internet. Non seulement il a permis de faire plus de choses dans le navigateur, mais il a aussi chang\u00e9 la vision g\u00e9n\u00e9rale du d\u00e9veloppement d'applications. Cependant, cette approche a n\u00e9cessit\u00e9 quelques am\u00e9liorations dans la maintenance du code des applications bas\u00e9es sur le navigateur. C'est \u00e0 cette \u00e9poque qu'ont \u00e9t\u00e9 d\u00e9velopp\u00e9s les premiers frameworks frontaux. Je vais en analyser deux \u00e0 la loupe aujourd'hui.","breadcrumb":{"@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#primaryimage","url":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/react_vs_vue.jpg","contentUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/react_vs_vue.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/thecodest.co\/blog\/an-objective-look-at-the-library-war-react-vs-vue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thecodest.co\/"},{"@type":"ListItem","position":2,"name":"An objective look at the library war: React vs Vue"}]},{"@type":"WebSite","@id":"https:\/\/thecodest.co\/#website","url":"https:\/\/thecodest.co\/","name":"The Codest","description":"","publisher":{"@id":"https:\/\/thecodest.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thecodest.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thecodest.co\/#organization","name":"The Codest","url":"https:\/\/thecodest.co\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thecodest.co\/#\/schema\/logo\/image\/","url":"https:\/\/thecodest.co\/app\/uploads\/2024\/03\/thecodest-logo.svg","contentUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/03\/thecodest-logo.svg","width":144,"height":36,"caption":"The Codest"},"image":{"@id":"https:\/\/thecodest.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pl.linkedin.com\/company\/codest","https:\/\/clutch.co\/profile\/codest"]},{"@type":"Person","@id":"https:\/\/thecodest.co\/#\/schema\/person\/7e3fe41dfa4f4e41a7baad4c6e0d4f76","name":"thecodest","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g","caption":"thecodest"},"url":"https:\/\/thecodest.co\/fr\/author\/thecodest\/"}]}},"_links":{"self":[{"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/posts\/3038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/comments?post=3038"}],"version-history":[{"count":5,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/posts\/3038\/revisions"}],"predecessor-version":[{"id":7718,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/posts\/3038\/revisions\/7718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/media\/3039"}],"wp:attachment":[{"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/media?parent=3038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/categories?post=3038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thecodest.co\/fr\/wp-json\/wp\/v2\/tags?post=3038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}