{"id":3726,"date":"2019-09-04T11:25:00","date_gmt":"2019-09-04T11:25:00","guid":{"rendered":"http:\/\/the-codest.localhost\/blog\/httpsthecodest-cothecodestreview-4-weekly-software-engineering-juice\/"},"modified":"2026-04-27T09:53:50","modified_gmt":"2026-04-27T09:53:50","slug":"thecodestreview-4-wochentlicher-software-engineering-saft","status":"publish","type":"post","link":"https:\/\/thecodest.co\/de\/blog\/thecodestreview-4-weekly-software-engineering-juice\/","title":{"rendered":"TheCodestReview #4 - w\u00f6chentlicher Softwareentwicklungssaft"},"content":{"rendered":"<p>(In der n\u00e4chsten Folge werde ich das Thema Humor am Arbeitsplatz weiterverfolgen und etwas ausf\u00fchrlicher behandeln, einfach weil ich es kann. \"Warum so ernst?\").<\/p>\n<p>Apropos Zeit, seit meiner letzten Ver\u00f6ffentlichung sind 2 Wochen vergangen, also wird es Zeit f\u00fcr die 4. Folge unseres <strong>#TheCodestReview<\/strong> Serie.<\/p>\n<h2>Liste der Themen, die wir diese Woche behandeln:<\/h2>\n<ol>\n<li>S\u00fcchtig werden nach <a href=\"https:\/\/thecodest.co\/de\/blog\/conditional-component-visibility-in-react\/\">React<\/a><\/li>\n<li>Alles, was Sie schon immer \u00fcber View Caching wissen wollten in <a href=\"https:\/\/thecodest.co\/de\/blog\/ways-to-increase-your-rails-performance\/\">Schiene<\/a><\/li>\n<li>Der Engineering Manager als Master-Recruiter<\/li>\n<\/ol>\n<p>Der Kommentar zum View Caching, der von unserem Fullstack <a href=\"https:\/\/thecodest.co\/de\/blog\/hire-vue-js-developers\/\">Entwickler<\/a> und der Podcast des technischen Leiters, der von meiner Wenigkeit kommentiert wurde.<\/p>\n<p>Als allseits bekannter Paint-App-Meister und Bewunderer von GIFs und Memes, die wie Merci-Pralinen mehr als 1000 Worte sagen, habe ich beschlossen, dass ich von nun an hier eine Kostprobe davon geben werde. Und wisst ihr was?<\/p>\n<p><a href=\"https:\/\/tenor.com\/view\/you-think-you-can-stop-me-starwars-emperor-stopme-gif-10174472\">Darth Sidious Sie denken, Sie k\u00f6nnen mich aufhalten GIF<\/a> von <a href=\"https:\/\/tenor.com\/search\/darthsidious-gifs\">Darthsidious GIFs<\/a><\/p>\n<p>Das letzte Mal haben wir uns entschieden, StimulusReflex, das in der Branche f\u00fcr Aufsehen sorgt, in den Mittelpunkt zu r\u00fccken. <a href=\"https:\/\/thecodest.co\/de\/blog\/hire-ror-developer\/\">Rubinrot<\/a> Gemeinschaft als neues Kind im Block, das eine Alternative zur Verwendung moderner <a href=\"https:\/\/thecodest.co\/de\/blog\/hire-javascript-developer\/\">Javascript<\/a> Frameworks in Rails-Projekten, um einen Overkill zu vermeiden.<\/p>\n<p>Siehe: <a href=\"https:\/\/www.linkedin.com\/posts\/codest_how-to-easily-start-with-stimulusreflex-activity-6732600588527296512-BDDO\">StimulusReflex alias ReactiveRails<\/a><\/p>\n<p>Um es zu einem Kampf auf Augenh\u00f6he zu machen, wollte ich React einen Gegenschlag gegen Stimulus machen lassen. Da ich auch daf\u00fcr bekannt bin, dass ich immer tue, was ich sage und meine Versprechen einhalte, geht es los:<\/p>\n<p><em>In der n\u00e4chsten Folge habe ich das Vergn\u00fcgen, einen Gastbeitrag von React Ingenieur von Vinted.com anzuk\u00fcndigen. F\u00fcr diejenigen unter Ihnen, die noch nie von Vinted geh\u00f6rt haben (die Wahrscheinlichkeit ist gering, aber dennoch m\u00f6glich): Vinted ist ein Modemarktplatz aus Vilnius, Litauen, der 2019 eine Einhorn-Bewertung erreicht hat. Die Plattform ist auf soliden <a href=\"https:\/\/thecodest.co\/de\/case-studies\/delivering-ruby-on-rails-talent-for-fast-integration\/\">Ruby on Rails<\/a> Stiftung, unterst\u00fctzt durch React auf dem Frontend-Teil.<\/em><\/p>\n<p>Nebenbei bemerkt: meine Frau ist absolut begeistert von Vinted und sie hat fast vollst\u00e4ndig aufgeh\u00f6rt, OLX als ihr prim\u00e4res Ziel f\u00fcr die Entr\u00fcmpelung unseres Kleiderschranks und den Verkauf gebrauchter Kleidung zu nutzen (sie war ein echter Fan) = <strong>IHR MACHT ES RICHTIG!<\/strong><\/p>\n<p>Es ist mir eine Ehre, einen ersten Gastbeitrag in unserer Reihe begr\u00fc\u00dfen zu d\u00fcrfen:<\/p>\n<p><a href=\"https:\/\/tenor.com\/view\/meryl-streep-yes-yeah-cheer-cheering-gif-5163144\">Meryl Streep Ja GIF<\/a> von <a href=\"https:\/\/tenor.com\/search\/merylstreep-gifs\">Merylstreep GIFs<\/a><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/ugnekryzeviciute\">Ugn\u0117 Kry\u017eevi\u010di\u016bt\u0117 - React Ingenieur von Vinted<\/a><\/p>\n<h2><a href=\"https:\/\/www.ladybug.dev\/episodes\/getting-hooked-on-react\">Sich an React binden<\/a> von LadyBug Podcast<\/h2>\n<p><em>Als ich den Titel des aktuellen LadyBug-Podcasts (\"Getting Hooked On React\") las, erwartete ich, dass es haupts\u00e4chlich um folgende Themen gehen w\u00fcrde <a href=\"https:\/\/thecodest.co\/de\/blog\/a-deeper-look-at-the-most-popular-react-hooks\/\">React-Haken<\/a>. Auch wenn der Podcast nicht tief in Hooks eintauchte, bot er doch eine hervorragende Einf\u00fchrung in die Grundlagen der React-Bibliothek f\u00fcr JavaScript.<\/em><\/p>\n<p><em>Ali und Emma vom LadyBug-Podcast besprechen die Besonderheiten von React - vom allgemeinen Aufbau der Bibliothek und ihren Vorteilen bis hin zu lebhaften Diskussionen \u00fcber Komponenten, <a href=\"https:\/\/thecodest.co\/de\/blog\/app-data-collection-security-risks-value-and-types-explored\/\">Daten<\/a> Handhabung, oder die <a href=\"https:\/\/thecodest.co\/de\/blog\/easy-guide-to-react-lifecycle\/\">React Lebenszyklus<\/a>und das alles mit einer Prise pers\u00f6nlicher Erfahrung. Es lohnt sich f\u00fcr jeden Front-End-Entwickler, der noch nicht die Gelegenheit hatte, die Wunder von React auszuprobieren.<\/em><\/p>\n<p><em>Meine erste Begegnung mit React war vor etwa drei Jahren, als ich meine Reise als Entwickler begann. Auch wenn Ali und Emma behaupten, dass React anfangs verwirrend sein k\u00f6nnte, fand ich es nach meiner eigenen Erfahrung relativ einfach, damit anzufangen, und es ist im Vergleich zu anderen Frontend-Frameworks wahrscheinlich am einfachsten zu erlernen. Es gibt jede Menge Tutorials, Artikel, Open-Source-Bibliotheken und andere Arten von Lernmaterial, die \u00fcberall verf\u00fcgbar sind. Allerdings sollte man sich der aktiven Entwicklung von React bewusst sein, wenn man solche Ressourcen durchsucht. Diese Episode des LadyBug-Podcasts bildet da keine Ausnahme - einige der erw\u00e4hnten Aspekte und Methoden sind bereits seit einiger Zeit veraltet. Daher ist es am besten, den Rat von Emma selbst zu befolgen und sich die neueste Dokumentation anzusehen.<\/em><\/p>\n<p><em>React hat sich stark weiterentwickelt und ist gereift, so dass <a href=\"https:\/\/thecodest.co\/de\/dictionary\/what-is-code-refactoring\/\">Code<\/a> Mit Hooks wird das Schreiben sogar noch einfacher, da Sie Zustands- und Lebenszyklusmethoden verwenden k\u00f6nnen, ohne Klassenkomponenten zu schreiben. Aber f\u00fcr Anf\u00e4nger - wie Ali treffend bemerkt - bringt die Vielfalt der M\u00f6glichkeiten, React zu schreiben (z. B. Klassen-\/Funktions-\/Hooks-Komponenten), zus\u00e4tzliche Komplexit\u00e4t mit sich, da es manchmal schwierig sein kann, zu erkennen, was vor sich geht. Au\u00dferdem kann es eine Herausforderung sein, herauszufinden, was man braucht, und relevante Informationen \u00fcber die Code-Implementierung zu finden.<\/em><\/p>\n<p><em>Als einen der Hauptvorteile von React hebt Ali hervor, dass es komponentenbasiert ist, was eine Modularisierung des Codes erm\u00f6glicht und die Zusammenarbeit mit anderen Entwicklern erleichtert. Au\u00dferdem ist die M\u00f6glichkeit, JSX zu verwenden, eine gro\u00dfartige visuelle Hilfe bei der Arbeit mit der Benutzeroberfl\u00e4che in JavaScript-Code - Sie brauchen keine separaten HTML-Dateien zu haben!<\/em><\/p>\n<p><em>Ali und Emma fassen auch sehr sch\u00f6n die Flexibilit\u00e4t zusammen, die ein Komponentensystem bietet. Ein hervorragendes Beispiel aus der Praxis ist mein Unternehmen Vinted, das ein schnelles Wachstum in Bezug auf die <a href=\"https:\/\/thecodest.co\/de\/dictionary\/how-to-make-product\/\">Produkt<\/a> sowie die <a href=\"https:\/\/thecodest.co\/de\/blog\/automotive-software-development-trends\/\">Entwicklungsteams<\/a> in den letzten Jahren daran gearbeitet. React hat enorme Vorteile gebracht - es hat Folgendes erm\u00f6glicht <a href=\"https:\/\/thecodest.co\/de\/blog\/why-us-companies-are-opting-for-polish-developers\/\">us<\/a> Wir k\u00f6nnen jetzt viel saubereren Code schreiben, wiederverwendbare UI-Komponenten verwenden und unseren Code leichter testen.<\/em><\/p>\n<p><em>Insgesamt bietet diese LadyBug-Podcast-Folge eine lebendige und charmante Diskussion \u00fcber die wichtigsten Aspekte von React. Ich empfehle sie jedem, der seine Reise mit React beginnt. Voller witziger Beispiele und Analogien zum wirklichen Leben, fesselt die Episode nahtlos die Aufmerksamkeit aller Zuh\u00f6rer, auch meine.<\/em><\/p>\n<p><article-inline-code-review><\/article-inline-code-review><\/p>\n<h2><a href=\"https:\/\/www.honeybadger.io\/blog\/ruby-rails-view-caching\/\">Rails Ansicht Caching<\/a> von Jonathan Miles von Honeybadger<\/h2>\n<p><em>Die Ansichten in Rails werden leider mit der Zeit immer langsamer. Das liegt daran, dass die Menge der in der Datenbank gespeicherten Objekte w\u00e4chst. Dies f\u00fchrt zu l\u00e4ngeren Abfragezeiten und nat\u00fcrlich auch zu l\u00e4ngeren Verarbeitungszeiten, wenn man etwas mit jedem der Objekte macht. Wenn das passiert, ist man nicht chancenlos, denn es gibt das Rails Views Caching.<\/em><\/p>\n<p><em>Dadurch k\u00f6nnen Sie viel Zeit sparen, indem Sie datenbanklastige Daten aus dem Cache laden (Laden einer einzelnen gespeicherten html-\u00e4hnlichen Datei statt Abfrage der Datenbank und Verarbeitung der Objekte). Bei verschiedenen Teilbereichen und Objekten kann man dies auch kosteng\u00fcnstiger gestalten - nat\u00fcrlich nur, wenn sich die Objekte nicht zu oft \u00e4ndern. Sie k\u00f6nnen auch versuchen, die zwischengespeicherten Objekte in einem separaten Teilbereich aufzubewahren - und so z.B. 19 von 20 Beitr\u00e4gen zu sparen, die gerendert werden (m\u00f6glicherweise mit einer Vielzahl von Feldern).<\/em><\/p>\n<p><em>Standardm\u00e4\u00dfig verwendet Rails Caching den file_store und speichert die gecachten Daten in den Ordnern. Allerdings werden alte Cache-Eintr\u00e4ge (die vielleicht schon lange abgelaufen sind) nicht gel\u00f6scht. Dies kann dazu f\u00fchren, dass die Dateimenge \u00fcberl\u00e4uft oder sogar der freie Platz auf dem Server knapp wird. Die andere Methode ist memory_store, die auch einige Nachteile hat (da der Cache auf einem einzigen Server gehalten wird). Sie kann auch die Menge des auf dem Server vorhandenen Arbeitsspeichers \u00fcberschreiten (oder den Mangel an Cache, wenn er st\u00e4ndig gel\u00f6scht wird). Aus diesem Grund ist der beste Caching-Mechanismus f\u00fcr gro\u00dfe Mengen die Memcached\/Redis-Methode. Dies gibt Ihnen die M\u00f6glichkeit, einen separaten Rechner f\u00fcr den Cache zu verwenden, der von allen Servern genutzt werden kann. Dadurch gibt es keine Probleme mit fehlendem Cache oder fehlendem Speicherplatz auf einem Server.<\/em><\/p>\n<p><em>Der Cache in Rails wird auf der Grundlage eines Bezeichners gef\u00fchrt, der entweder direkt als String angegeben werden kann oder automatisch generiert wird, wenn man ein Objekt an die Cache-Funktion \u00fcbergibt. Im Falle von Objekten ist es meistens das Attribut updated_at. Sie k\u00f6nnen auch einen statischen Schl\u00fcssel aus Objektparametern angeben.<\/em><\/p>\n<p><em>Eine andere Methode der Zwischenspeicherung ist die Verwendung von Javascript zur Aktualisierung eines Feldes, das einmal am Tag ge\u00e4ndert wird. Auf diese Weise k\u00f6nnen Sie immer ein g\u00fcltiges Datum anzeigen lassen, ohne die Website aktualisieren zu m\u00fcssen - was ziemlich gro\u00df oder langsam sein kann.<\/em><\/p>\n<h2><a href=\"https:\/\/www.mentoring-club.com\/events\/engineering-manager-master-recruiter\">Engineering Manager als Master Recruiter<\/a> von Mentoring Club<\/h2>\n<p>Ich m\u00f6chte Ihnen nicht zu viel verraten, aber die Podiumsdiskussion zum Thema \"Die Rolle des technischen Leiters im Einstellungsprozess\" ist sehr wertvoll f\u00fcr alle, die sich fragen, wann der richtige Zeitpunkt f\u00fcr den technischen Leiter gekommen ist, um in den Bewerbungsprozess einzusteigen. Unter <a href=\"https:\/\/thecodest.co\/\">Codest<\/a>Wir praktizieren sozusagen das, was die Diskussionsteilnehmer predigen, und unsere <a href=\"https:\/\/thecodest.co\/de\/blog\/guide-to-enterprise-software-development\/\">CTO<\/a> ist die 1. Anlaufstelle f\u00fcr <a href=\"https:\/\/thecodest.co\/de\/blog\/team-extension-guide-software-development\/\">Ingenieure<\/a> die sich bei uns bewerben, w\u00e4hrend in der n\u00e4chsten Phase die Interviews von <a href=\"https:\/\/thecodest.co\/de\/blog\/how-to-hire-the-best-outsourced-development-team-for-a-scaleup\/\">Team<\/a> Manager, mit denen die potenziellen neuen Mitarbeiter eng zusammenarbeiten werden. Ein paar umsetzbare Ratschl\u00e4ge, die Sie sofort anwenden k\u00f6nnen, um Ihr Einstellungsspiel als technischer Leiter zu verbessern:<\/p>\n<ol>\n<li>\n<p>\u00dcberpr\u00fcfen Sie Ihren Prozess und stellen Sie sicher, dass Sie sich so fr\u00fch wie m\u00f6glich in den Prozess einklinken. Idealerweise sind Sie der erste Kontaktpunkt f\u00fcr die Bewerber, da der erste Eindruck eine entscheidende Rolle dabei spielt, wie Ihr Unternehmen von den besten Talenten wahrgenommen wird.<\/p>\n<\/li>\n<li>\n<p>Wenden Sie sich an hocheffektive Personalverantwortliche in Ihrem Unternehmen (vielleicht an denjenigen, der Sie damals eingestellt hat) und fragen Sie, ob Sie bei einigen ihrer geplanten Vorstellungsgespr\u00e4che hospitieren k\u00f6nnen, pr\u00fcfen Sie ihre Techniken und fragen Sie nach Tipps. Beobachten und lernen Sie. Gehen Sie in jedes Vorstellungsgespr\u00e4ch mit echter Neugierde auf die Bewerber.<\/p>\n<\/li>\n<li>\n<p>Suchen Sie nach Potenzial und stellen Sie Mitarbeiter mit Potenzial und der F\u00e4higkeit zu schnellem Wachstum ein.<\/p>\n<\/li>\n<li>\n<p>Sprechen Sie Ihre Stellenanzeigen mit all Ihren Ingenieuren durch und fragen Sie sie, ob sie sich auf die Stelle bewerben w\u00fcrden. Wenn nicht, fragen Sie sie, was sie st\u00f6rt, und beziehen Sie ihr Feedback in die 2.0-Stellenanzeige ein, die Sie in den Stellenb\u00f6rsen ver\u00f6ffentlichen werden.\u00a0<\/p>\n<\/li>\n<li>\n<p>Betrachten Sie das erste Vorstellungsgespr\u00e4ch als eine Gelegenheit, eine gute Beziehung zu Ihren potenziellen k\u00fcnftigen Kollegen aufzubauen.<\/p>\n<\/li>\n<\/ol>\n<p>Ich empfehle Ihnen, sich das ganze Video-Panel anzuschauen, aber wenn Sie auf Podcasts stehen und gerne w\u00e4hrend des Autofahrens, der Arbeit oder des Abwaschs zuh\u00f6ren, haben Sie hier auch ein Spotify <a href=\"https:\/\/open.spotify.com\/episode\/0kguAIi6XIysXpkhdfeZpR?si=Fo4oBCudQTuvVKvzUQ_N1w\">Link.<\/a>\u00a0<\/p>\n<p>Vielen Dank f\u00fcrs Lesen, und wenn Sie so weit gekommen sind, wei\u00df ich Ihre Zeit zu sch\u00e4tzen, und jegliches Feedback (egal, ob cool oder abwertend) ist mehr als willkommen auf <a href=\"https:\/\/www.linkedin.com\/in\/kamilferens\/\">LinkedIn<\/a> oder an meine <a href=\"mailto:kamil.ferens@thecodest.co\">E-Mail<\/a>.\u00a0<\/p>\n<p>Die n\u00e4chste Folge kommt bald wieder zu Ihnen!\u00a0<\/p>\n<p><a href=\"https:\/\/tenor.com\/view\/yippie-iwill-see-you-soon-dancing-baby-sunglasses-toddler-gif-17483936\">Yippie IWill See You Soon Tanzen GIF<\/a> von <a href=\"https:\/\/tenor.com\/search\/yippieiwillseeyousoon-gifs\">Yippieiwillseeyousoon GIFs<\/a><\/p>\n<p><article-software-consulting><\/article-software-consulting><\/p>\n<p><strong>Lesen Sie mehr:<\/strong><\/p>\n<p><a href=\"https:\/\/thecodest.co\/blog\/the-codest-review3-weekly-software-engineering-juice\/\">TheCodestReview #3 - w\u00f6chentlicher Softwareentwicklungssaft<\/a><\/p>\n<p><a href=\"https:\/\/thecodest.co\/blog\/thecodestreview-2-weekly-software-engineering-juice\/\">TheCodestReview #2 - w\u00f6chentlicher Softwareentwicklungssaft<\/a><\/p>\n<p><a href=\"https:\/\/thecodest.co\/blog\/thecodestreview-1-weekly-software-engineering-juice\/\">TheCodestReview #1 - w\u00f6chentlicher Softwareentwicklungssaft<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Man sagt, die Zeit vergeht schnell, wenn man Spa\u00df hat. F\u00fcr mich pers\u00f6nlich ist der Spa\u00df an der Sache besonders wichtig, wenn es um die Gr\u00fcndung und das Wachstum eines Unternehmens geht. Er sorgt daf\u00fcr, dass ich mich selbst genie\u00dfe, egal wie viel meiner inneren Energieressourcen von der w\u00f6chentlichen Hektik aufgezehrt werden.<\/p>","protected":false},"author":2,"featured_media":3727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software-development"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TheCodestReview #4 - weekly software engineering juice - The Codest<\/title>\n<meta name=\"description\" content=\"They say time flies fast when you are having fun. For me personally, the fun part is especially important in everyday startup and business growth ride. It makes me enjoy myself no matter how much of my inner energy resources are eaten out by week to week hustle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thecodest.co\/de\/blog\/thecodestreview-4-wochentlicher-software-engineering-saft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TheCodestReview #4 - weekly software engineering juice\" \/>\n<meta property=\"og:description\" content=\"They say time flies fast when you are having fun. For me personally, the fun part is especially important in everyday startup and business growth ride. It makes me enjoy myself no matter how much of my inner energy resources are eaten out by week to week hustle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thecodest.co\/de\/blog\/thecodestreview-4-wochentlicher-software-engineering-saft\/\" \/>\n<meta property=\"og:site_name\" content=\"The Codest\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-04T11:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T09:53:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/the-codest-software-engineering.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"thecodest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"thecodest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/\"},\"author\":{\"name\":\"thecodest\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/person\\\/7e3fe41dfa4f4e41a7baad4c6e0d4f76\"},\"headline\":\"TheCodestReview #4 &#8211; weekly software engineering juice\",\"datePublished\":\"2019-09-04T11:25:00+00:00\",\"dateModified\":\"2026-04-27T09:53:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/\"},\"wordCount\":1663,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/the-codest-software-engineering.png\",\"articleSection\":[\"Software Development\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/\",\"url\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/\",\"name\":\"TheCodestReview #4 - weekly software engineering juice - The Codest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/the-codest-software-engineering.png\",\"datePublished\":\"2019-09-04T11:25:00+00:00\",\"dateModified\":\"2026-04-27T09:53:50+00:00\",\"description\":\"They say time flies fast when you are having fun. For me personally, the fun part is especially important in everyday startup and business growth ride. It makes me enjoy myself no matter how much of my inner energy resources are eaten out by week to week hustle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/the-codest-software-engineering.png\",\"contentUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/05\\\/the-codest-software-engineering.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/blog\\\/thecodestreview-4-weekly-software-engineering-juice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thecodest.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TheCodestReview #4 &#8211; weekly software engineering juice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#website\",\"url\":\"https:\\\/\\\/thecodest.co\\\/\",\"name\":\"The Codest\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thecodest.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#organization\",\"name\":\"The Codest\",\"url\":\"https:\\\/\\\/thecodest.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/03\\\/thecodest-logo.svg\",\"contentUrl\":\"https:\\\/\\\/thecodest.co\\\/app\\\/uploads\\\/2024\\\/03\\\/thecodest-logo.svg\",\"width\":144,\"height\":36,\"caption\":\"The Codest\"},\"image\":{\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pl.linkedin.com\\\/company\\\/codest\",\"https:\\\/\\\/clutch.co\\\/profile\\\/codest\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thecodest.co\\\/#\\\/schema\\\/person\\\/7e3fe41dfa4f4e41a7baad4c6e0d4f76\",\"name\":\"thecodest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g\",\"caption\":\"thecodest\"},\"url\":\"https:\\\/\\\/thecodest.co\\\/de\\\/author\\\/thecodest\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TheCodestReview #4 - w\u00f6chentlicher Softwareentwicklungssaft - The Codest","description":"Man sagt, die Zeit vergeht schnell, wenn man Spa\u00df hat. F\u00fcr mich pers\u00f6nlich ist der Spa\u00df an der Sache besonders wichtig, wenn es um die Gr\u00fcndung und das Wachstum eines Unternehmens geht. Er sorgt daf\u00fcr, dass ich mich selbst genie\u00dfe, egal wie viel meiner inneren Energieressourcen von der w\u00f6chentlichen Hektik aufgezehrt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thecodest.co\/de\/blog\/thecodestreview-4-wochentlicher-software-engineering-saft\/","og_locale":"de_DE","og_type":"article","og_title":"TheCodestReview #4 - weekly software engineering juice","og_description":"They say time flies fast when you are having fun. For me personally, the fun part is especially important in everyday startup and business growth ride. It makes me enjoy myself no matter how much of my inner energy resources are eaten out by week to week hustle.","og_url":"https:\/\/thecodest.co\/de\/blog\/thecodestreview-4-wochentlicher-software-engineering-saft\/","og_site_name":"The Codest","article_published_time":"2019-09-04T11:25:00+00:00","article_modified_time":"2026-04-27T09:53:50+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/the-codest-software-engineering.png","type":"image\/png"}],"author":"thecodest","twitter_card":"summary_large_image","twitter_misc":{"Written by":"thecodest","Est. reading time":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#article","isPartOf":{"@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/"},"author":{"name":"thecodest","@id":"https:\/\/thecodest.co\/#\/schema\/person\/7e3fe41dfa4f4e41a7baad4c6e0d4f76"},"headline":"TheCodestReview #4 &#8211; weekly software engineering juice","datePublished":"2019-09-04T11:25:00+00:00","dateModified":"2026-04-27T09:53:50+00:00","mainEntityOfPage":{"@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/"},"wordCount":1663,"commentCount":0,"publisher":{"@id":"https:\/\/thecodest.co\/#organization"},"image":{"@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#primaryimage"},"thumbnailUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/the-codest-software-engineering.png","articleSection":["Software Development"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/","url":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/","name":"TheCodestReview #4 - w\u00f6chentlicher Softwareentwicklungssaft - The Codest","isPartOf":{"@id":"https:\/\/thecodest.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#primaryimage"},"image":{"@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#primaryimage"},"thumbnailUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/the-codest-software-engineering.png","datePublished":"2019-09-04T11:25:00+00:00","dateModified":"2026-04-27T09:53:50+00:00","description":"Man sagt, die Zeit vergeht schnell, wenn man Spa\u00df hat. F\u00fcr mich pers\u00f6nlich ist der Spa\u00df an der Sache besonders wichtig, wenn es um die Gr\u00fcndung und das Wachstum eines Unternehmens geht. Er sorgt daf\u00fcr, dass ich mich selbst genie\u00dfe, egal wie viel meiner inneren Energieressourcen von der w\u00f6chentlichen Hektik aufgezehrt werden.","breadcrumb":{"@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#primaryimage","url":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/the-codest-software-engineering.png","contentUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/05\/the-codest-software-engineering.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/thecodest.co\/blog\/thecodestreview-4-weekly-software-engineering-juice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thecodest.co\/"},{"@type":"ListItem","position":2,"name":"TheCodestReview #4 &#8211; weekly software engineering juice"}]},{"@type":"WebSite","@id":"https:\/\/thecodest.co\/#website","url":"https:\/\/thecodest.co\/","name":"Der Codest","description":"","publisher":{"@id":"https:\/\/thecodest.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thecodest.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thecodest.co\/#organization","name":"Der Codest","url":"https:\/\/thecodest.co\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thecodest.co\/#\/schema\/logo\/image\/","url":"https:\/\/thecodest.co\/app\/uploads\/2024\/03\/thecodest-logo.svg","contentUrl":"https:\/\/thecodest.co\/app\/uploads\/2024\/03\/thecodest-logo.svg","width":144,"height":36,"caption":"The Codest"},"image":{"@id":"https:\/\/thecodest.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pl.linkedin.com\/company\/codest","https:\/\/clutch.co\/profile\/codest"]},{"@type":"Person","@id":"https:\/\/thecodest.co\/#\/schema\/person\/7e3fe41dfa4f4e41a7baad4c6e0d4f76","name":"thecodest","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5dbfe6a1e8c86e432e8812759e34e6fe82ebac75119ae3237a6c1311fa19caf4?s=96&d=mm&r=g","caption":"thecodest"},"url":"https:\/\/thecodest.co\/de\/author\/thecodest\/"}]}},"_links":{"self":[{"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/posts\/3726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/comments?post=3726"}],"version-history":[{"count":3,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/posts\/3726\/revisions"}],"predecessor-version":[{"id":8063,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/posts\/3726\/revisions\/8063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/media\/3727"}],"wp:attachment":[{"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/media?parent=3726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/categories?post=3726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thecodest.co\/de\/wp-json\/wp\/v2\/tags?post=3726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}